{"id":4211,"date":"2024-11-20T10:28:13","date_gmt":"2024-11-20T08:28:13","guid":{"rendered":"https:\/\/healthandfood.taltech.ee\/liige\/rasmus-kasper\/"},"modified":"2025-04-29T14:24:56","modified_gmt":"2025-04-29T11:24:56","slug":"rasmus-kasper","status":"publish","type":"member","link":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/","title":{"rendered":"Rasmus K\u00e4sper"},"featured_media":0,"template":"","class_list":["post-4211","member","type-member","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rasmus K\u00e4sper - Health and Food Technologies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rasmus K\u00e4sper - Health and Food Technologies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/\" \/>\n<meta property=\"og:site_name\" content=\"Health and Food Technologies\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T11:24:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/member\\\/rasmus-kasper\\\/\",\"url\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/member\\\/rasmus-kasper\\\/\",\"name\":\"Rasmus K\u00e4sper - Health and Food Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#website\"},\"datePublished\":\"2024-11-20T08:28:13+00:00\",\"dateModified\":\"2025-04-29T11:24:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/member\\\/rasmus-kasper\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/member\\\/rasmus-kasper\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/member\\\/rasmus-kasper\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rasmus K\u00e4sper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/\",\"name\":\"Tervise- ja toidutehnoloogiate fookustippkeskus\",\"description\":\"Health and food technology activities\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#organization\",\"name\":\"TalTech\",\"url\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-taltech-favorites.webp\",\"contentUrl\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-taltech-favorites.webp\",\"width\":512,\"height\":512,\"caption\":\"TalTech\"},\"image\":{\"@id\":\"https:\\\/\\\/healthandfood.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rasmus K\u00e4sper - Health and Food Technologies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/","og_locale":"en_US","og_type":"article","og_title":"Rasmus K\u00e4sper - Health and Food Technologies","og_url":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/","og_site_name":"Health and Food Technologies","article_modified_time":"2025-04-29T11:24:56+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/","url":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/","name":"Rasmus K\u00e4sper - Health and Food Technologies","isPartOf":{"@id":"https:\/\/healthandfood.taltech.ee\/en\/#website"},"datePublished":"2024-11-20T08:28:13+00:00","dateModified":"2025-04-29T11:24:56+00:00","breadcrumb":{"@id":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/healthandfood.taltech.ee\/en\/member\/rasmus-kasper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/healthandfood.taltech.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Rasmus K\u00e4sper"}]},{"@type":"WebSite","@id":"https:\/\/healthandfood.taltech.ee\/en\/#website","url":"https:\/\/healthandfood.taltech.ee\/en\/","name":"Tervise- ja toidutehnoloogiate fookustippkeskus","description":"Health and food technology activities","publisher":{"@id":"https:\/\/healthandfood.taltech.ee\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthandfood.taltech.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/healthandfood.taltech.ee\/en\/#organization","name":"TalTech","url":"https:\/\/healthandfood.taltech.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/healthandfood.taltech.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/healthandfood.taltech.ee\/wp-content\/uploads\/2024\/12\/cropped-taltech-favorites.webp","contentUrl":"https:\/\/healthandfood.taltech.ee\/wp-content\/uploads\/2024\/12\/cropped-taltech-favorites.webp","width":512,"height":512,"caption":"TalTech"},"image":{"@id":"https:\/\/healthandfood.taltech.ee\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/healthandfood.taltech.ee\/en\/wp-json\/wp\/v2\/member\/4211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthandfood.taltech.ee\/en\/wp-json\/wp\/v2\/member"}],"about":[{"href":"https:\/\/healthandfood.taltech.ee\/en\/wp-json\/wp\/v2\/types\/member"}],"wp:attachment":[{"href":"https:\/\/healthandfood.taltech.ee\/en\/wp-json\/wp\/v2\/media?parent=4211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}